{"id":988065,"date":"2022-09-12T15:16:04","date_gmt":"2022-09-12T14:16:04","guid":{"rendered":"https:\/\/canvalles.com\/?page_id=988065"},"modified":"2023-08-25T19:06:33","modified_gmt":"2023-08-25T18:06:33","slug":"condiciones-de-compra","status":"publish","type":"page","link":"https:\/\/canvalles.com\/ca\/condiciones-de-compra\/","title":{"rendered":"Condiciones de Compra"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"988065\" class=\"elementor elementor-988065\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-101d3b4 elementor-section-height-min-height elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"101d3b4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1574e4\" data-id=\"a1574e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bad2e38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bad2e38\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d49eec\" data-id=\"3d49eec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3502209 elementor-widget elementor-widget-text-editor\" data-id=\"3502209\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Condicions de compra <\/strong><\/p>\n<p>Estas condiciones constituyen las condiciones generales de compra de la compa\u00f1\u00eda Can Vall\u00e8s S.L.U (en adelante, Can Vall\u00e8s) que comercializa los productos a trav\u00e9s del sitio web http:\/\/canvalles.com<\/p>\n<p><\/p>\n<p>1.- Objeto y generalidades<\/p>\n<p>Las presentes Condiciones Generales de Contrataci\u00f3n (en adelante, las \u201cCondiciones Generales\u201d), junto con las condiciones particulares que puedan establecerse, regulan las condiciones de compra de productos a trav\u00e9s del sitio web www.canvalles.com (en adelante, el \u201cSitio Web\u201d o el \u201cPortal\u201d),\u00a0 titularidad de Can Valles S.L. (en adelante Can Valles), cuyo domicilio social se encuentra en calle Cantarellas 2, 8731, Sant Marti Sarroca (Barcelona)<br>El uso de los servicios del Sitio Web, as\u00ed como la adquisici\u00f3n de cualquiera de los productos ofertados, supone la aceptaci\u00f3n del Usuario, sin reservas de ninguna clase, de todas y cada una de las presentes Condiciones Generales. El registro en el Portal y el uso de los servicios conlleva que sus datos como Usuario pasar\u00e1n a formar parte de los ficheros de Can Valles, y su tratamiento ser\u00e1 conforme a lo previsto en la Pol\u00edtica de Privacidad, que el Usuario declara expresamente conocer y aceptar.<br>CAN VALLES proporciona informaci\u00f3n acerca de productos, y ofrece la posibilidad de su adquisici\u00f3n a trav\u00e9s del Sitio Web. Las personas que pretendan adquirir productos deben tener la condici\u00f3n de \u201cUsuario Registrado\u201d o de \u201cUsuario Invitado\u201d, las cuales se adquieren completando el respectivo formulario de registro previo al proceso de compra y siguiendo los pasos que CAN VALLES posteriormente comunica a trav\u00e9s del Sitio Web.<\/p>\n<p>Las presentes Condiciones Generales, junto con el Aviso Legal y la Pol\u00edtica de Privacidad del Sitio Web, son las \u00fanicas condiciones aplicables al uso del Portal y a la compra de los productos a trav\u00e9s del mismo y sustituyen a cualesquiera otras condiciones, salvo previo acuerdo y por escrito entre Can Valles y el Usuario. En consecuencia, el Usuario que acceda al Sitio Web, se registre y realice la compra de productos a trav\u00e9s del Portal acepta someterse y queda vinculado por las Condiciones Generales, el Aviso Legal y la Pol\u00edtica de Privacidad tal y como se hallen redactadas en el momento en que se acceda al Sitio Web.<br>Todo Usuario que se registre al Sitio Web debe tener, al menos, dieciocho (18) a\u00f1os.<\/p>\n<p><\/p>\n<p>2.- Informaci\u00f3n sobre los productos<br>Las fotograf\u00edas, representaciones gr\u00e1ficas o iconogr\u00e1ficas y v\u00eddeos relativos a los Productos de Can Valles, as\u00ed como nombres comerciales, marcas o signos distintivos de cualquier clase contenidos en el Sitio Web, tienen por objeto aportar la mayor informaci\u00f3n, no obstante, el Usuario ha de tener en cuenta que tienen un prop\u00f3sito orientativo y, en consecuencia, carecen de car\u00e1cter exhaustivo.<br>Can Valles se reserva el derecho a decidir, en cada momento, los productos ofrecidos a los Usuarios a trav\u00e9s del Portal. De este modo, Can Valles podr\u00e1 en cualquier momento a\u00f1adir nuevos productos a los incluidos en el Portal, entendi\u00e9ndose, salvo que se disponga otra cosa, que tales nuevos productos se regir\u00e1n por lo dispuesto en las Condiciones Generales\u00a0 que se encuentren en vigor en ese momento.<br>Asimismo, Can Valles se reserva el derecho a dejar de facilitar el acceso, en cualquier momento y sin previo aviso, a cualquiera de los productos ofrecidos en el Portal.<br>En el caso en que, por circunstancias de fuerza mayor, un producto no est\u00e9 disponible despu\u00e9s de haberse realizado la compra, Can Valles informar\u00e1 al Usuario por email de la anulaci\u00f3n total o, en su caso, parcial del pedido. La anulaci\u00f3n parcial del pedido no da derecho a la anulaci\u00f3n de la totalidad del pedido, sin perjuicio del ejercicio del derecho de desistimiento que corresponde al Usuario de conformidad con lo establecido en las presentes Condiciones Generales.<\/p>\n<p><\/p>\n<p>3.- Sistema de compra de los productos<br>Para proceder a la compra del producto, el Usuario registrado o invitado, que deber\u00e1 ser mayor de dieciocho (18) a\u00f1os, deber\u00e1 seleccionar el producto que desea comprar y a\u00f1adirlo a la Cesta de la Compra. Una vez completada la selecci\u00f3n de productos objeto de compra, el Usuario deber\u00e1 pulsar el icono \u201cTerminar\u201d. A continuaci\u00f3n, se indicar\u00e1n los productos seleccionados para su compra y el Usuario deber\u00e1 seleccionar entre el env\u00edo de los productos al domicilio introducido en sus datos de registro. Por \u00faltimo, el usuario deber\u00e1 pulsar el icono \u201cPagar\u201d<br>El nombre de Usuario, la direcci\u00f3n de correo electr\u00f3nico\u00a0 y la contrase\u00f1a facilitados a Can Valles son elementos identificadores y habilitadores para acceder y efectuar las compras y tienen car\u00e1cter personal e intransferible. El nombre del Usuario, la contrase\u00f1a y la direcci\u00f3n de correo electr\u00f3nico podr\u00e1n ser modificados,\u00a0 en cuyo caso la contrase\u00f1a, nombre de Usuario y\/o direcci\u00f3n de correo electr\u00f3nico modificadas perder\u00e1n su validez.<br>Una vez finalizado el proceso de compra Can Valles remitir\u00e1 al correo electr\u00f3nico facilitado por el Usuario, un email de confirmaci\u00f3n de la recepci\u00f3n del pedido dentro de las veinticuatro (24) horas siguientes a la realizaci\u00f3n del mismo. La confirmaci\u00f3n del pedido remitida por Can Valles no tendr\u00e1 validez como factura, s\u00f3lo como comprobante de compra. El Departamento de Atenci\u00f3n al Cliente de Can Valles remitir\u00e1 al Usuario la correspondiente factura\u00a0 en un plazo inferior a treinta (30) d\u00edas desde la ejecuci\u00f3n de la compra.<\/p>\n<p><\/p>\n<p>4.- Precios de los productos<br>Los precios de los productos que se ofrecen a trav\u00e9s del Sitio Web incluyen todos los impuestos aplicables. Los gastos de env\u00edo de los productos por cuenta del comprador, se detallar\u00e1n y desglosar\u00e1n en la secci\u00f3n \u201cTu Cesta\u201d del Sitio Web.<br>Can Valles se reserva el derecho a modificar los precios reflejados en el Sitio Web, en cualquier momento. Los productos se facturar\u00e1n al precio en vigor reflejado en el Sitio Web, en el momento del registro del pedido.<br>Los precios pueden variar de un canal a otro de Can Valles, pudiendo haber, por ejemplo, diferencias entre el precio web y el de las tiendas f\u00edsicas. Pueden existir promociones que s\u00f3lo afecten a uno de los canales. Cada canal (tienda) se reserva el derecho a realizar promociones propias.<\/p>\n<p><\/p>\n<p>5.- Pago de los productos<br>El pago del precio de los bienes comprados y de los gastos de env\u00edo, los cuales aparecer\u00e1n en pantalla, se podr\u00e1 realizar mediante tarjeta de cr\u00e9dito o d\u00e9bito y mediante otros sistemas de pago indicados en cada momento en el Sitio Web.<br>Para proceder al pago, el Usuario deber\u00e1 seguir las instrucciones que aparecen en pantalla en funci\u00f3n del sistema de pago elegido.<br>Como sistema de pago electr\u00f3nico, Can Valles est\u00e1 adscrita a la pasarela de pago de comercio electr\u00f3nico. Todos los datos proporcionados a estos efectos son encriptados bajo el protocolo SSL (Secure Socket Layers) para garantizar la m\u00e1xima seguridad de los mismos.<br>El Usuario deber\u00e1 notificar a Can Valles, a trav\u00e9s de canvalles@canvalles.com cualquier cargo indebido o fraudulento en la cuenta proporcionada para compras en el Sitio Web, en el menor plazo de tiempo posible, con el objeto de que Can Valles pueda realizar las gestiones que considere convenientes.<\/p>\n<p><\/p>\n<p>6.- Entrega de los productos<br>Entrega dentro de las primeras 24\/48h (seg\u00fan disponibilidad) despu\u00e9s de haber realizado el pedido. La entrega se realizar\u00e1, en el domicilio se\u00f1alado a tal efecto en el proceso de registro en la web, no se entregar\u00e1n productos en apartados de correos ni locutorios. Can Valles no entrega en Ceuta, Melilla, Canarias, ni Baleares.<br>Can Valles no ser\u00e1 responsable por los errores o perjuicios causados en la entrega cuando la direcci\u00f3n de entrega facilitada por el Usuario no se ajuste al lugar de entrega deseado por el mismo.<\/p>\n<p><\/p>\n<p>7.- Devoluci\u00f3n de productos<br>(i) Derecho de desistimiento<br>El Usuario dispondr\u00e1 de un plazo m\u00e1ximo de catorce (14) d\u00edas naturales desde la entrega del producto para desistir, total o parcialmente, de la compra del producto, de conformidad con la legislaci\u00f3n aplicable.<br>Una vez finalizado el plazo de catorce (14) d\u00edas naturales, Can Valles no aceptar\u00e1 devoluciones por desistimiento de compras de productos.<br>En el supuesto de desistir de la compra de un producto, el Usuario deber\u00e1 ponerse en contacto con Can Valles mediante el env\u00edo de un correo electr\u00f3nico a canvalles@canvalles.com. <br>En todo caso, en el supuesto de desistir de la compra, deber\u00e1n cumplirse los siguientes requisitos:<br>1) El producto debe estar en el mismo estado en que se entreg\u00f3 y deber\u00e1 conservar su embalaje y etiquetado original.<br>2) La devoluci\u00f3n a Can Valles debe hacerse usando la misma caja o sobre utilizado en la entrega o, en su defecto, en alg\u00fan formato similar que garantice la devoluci\u00f3n de los productos en perfecto estado.<br>3) Deber\u00e1 incluirse una copia del justificante de compra y del albar\u00e1n de entrega de los productos dentro del paquete, donde adem\u00e1s se indiquen los productos devueltos y el motivo de la devoluci\u00f3n.<br>Las devoluciones de los pedidos deber\u00e1n remitirse a la direcci\u00f3n de Can Valles, calle Cantarellas 2, 8731, Sant Marti Sarroca (Barcelona). El Usuario asumir\u00e1 los gastos de env\u00edo por devoluci\u00f3n en caso de ejercicio del derecho de desistimiento.<br>(ii) Devoluci\u00f3n de productos defectuosos<br>Sin perjuicio de cualesquiera otros derechos que pudieran corresponderle, el Usuario tendr\u00e1 derecho al reembolso del precio de los productos defectuosos o de los productos entregados si no se corresponden con el pedido realizado por el Usuario. Alternativamente a lo anterior, el Usuario tendr\u00e1 derecho a reclamar, y que se le entregue, un producto igual, en perfecto estado.<br>En los supuestos de devoluci\u00f3n a Can Valles de productos defectuosos o que no se corresponden con su pedido, \u00e9sta deber\u00e1 realizarse por parte del Usuario mediante el procedimiento establecido en el apartado (i) anterior, si bien el Usuario, en este caso, no deber\u00e1 hacer frente a los costes de devoluci\u00f3n de dichos productos.<br>Siempre que el Usuario haya seguido el procedimiento establecido en el apartado (i) anterior y se hayan cumplido los requisitos establecidos en este apartado, Can Valles reembolsar\u00e1 el precio abonado correspondiente a los productos devueltos que sean defectuosos o que no se correspondan con el pedido de productos realizado por el Usuario, conforme a lo establecido en el apartado (iii) posterior.<br>(iii) Reembolso del precio de los productos al Usuario<br>Siempre que el Usuario haya seguido el procedimiento establecido en este apartado y se hayan cumplido los requisitos establecidos en el mismo, Can Valles reembolsar\u00e1 el precio abonado por el Usuario correspondiente a los productos devueltos. En el caso de que la devoluci\u00f3n se realice en ejercicio del derecho de desistimiento del Usuario descrito en el apartado (i) Can Valles no abonar\u00e1 ni har\u00e1 frente a los gastos y\/o costes de devoluci\u00f3n.<br>El Usuario no tendr\u00e1 derecho al reembolso del precio de los productos devueltos que no se hallen en las mismas condiciones en que fueron entregados, o no se hayan cumplido los requisitos establecidos en las presentes Condiciones Generales.<br>Las devoluciones parciales de un pedido dar\u00e1n lugar al reembolso del precio correspondiente al producto o productos efectivamente devueltos.<br>Can Valles gestionar\u00e1 la orden de devoluci\u00f3n del precio mediante el mismo sistema de pago utilizado por el Usuario para la adquisici\u00f3n de los productos, en un plazo de treinta (30) d\u00edas desde la recogida del pedido devuelto y una vez Can Valles haya comprobado que los productos objeto de devoluci\u00f3n cumplen con los requisitos establecidos en los apartados (i) y (ii) anteriores. La aplicaci\u00f3n de la devoluci\u00f3n del precio en la cuenta del Usuario depender\u00e1 de la entidad bancaria.<\/p>\n<p><\/p>\n<p>&nbsp;8.- Modificaci\u00f3n de las Condiciones Generales<br>Can Valles se reserva el derecho de modificar, en cualquier momento y sin previo aviso, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web, as\u00ed como las Condiciones Generales. Los Usuarios siempre dispondr\u00e1n de estas Condiciones Generales en un sitio visible, libremente accesible para cuantas consultas quiera realizar. Los Usuarios se comprometen a leer atentamente estas Condiciones Generales cada vez que accedan a la tienda del Sitio Web. En cualquier caso, la aceptaci\u00f3n de las Condiciones Generales ser\u00e1 un paso previo e indispensable a la contrataci\u00f3n de cualquier producto disponible a trav\u00e9s del Sitio Web.<\/p>\n<p>&nbsp;9.- Comunicaciones entre Can Valles y el Usuario<br>Todas las comunicaciones entre Can Valles y el Usuario relativas a estas Condiciones Generales o a la adquisici\u00f3n de los productos a trav\u00e9s del Sitio Web, se realizar\u00e1n por escrito y de conformidad con los procedimientos de comunicaci\u00f3n establecidos en estas Condiciones Generales para cada caso en particular.<br>Para el resto de supuestos que no est\u00e9n expresamente regulados en estas Condiciones Generales, las comunicaciones que el Usuario pretenda remitir a Can Valles se dirigir\u00e1n a la direcci\u00f3n de Can Valles indicada en la Condici\u00f3n Primera y se realizar\u00e1n por escrito y mediante un sistema que permita acreditar el contenido y la recepci\u00f3n por parte Can Valles de la correspondiente comunicaci\u00f3n.<\/p>\n<p><\/p>\n<p>10.- Integridad de las Condiciones Generales<br>Las presentes Condiciones Generales, la Pol\u00edtica de Privacidad y el Aviso Legal constituyen la expresa y \u00fanica voluntad de Can Valles y el Usuario en relaci\u00f3n con su objeto e invalida y sustituye cualesquiera otros acuerdos o contratos, verbales o por escrito, alcanzados por las partes con anterioridad.<\/p>\n<p><\/p>\n<p>11.- Nulidad parcial<br>En caso de que cualquier Cl\u00e1usula de las presentes Condiciones Generales sea declarada nula, se proceder\u00e1 a la retirada o sustituci\u00f3n de la misma. En cualquier caso, dicha declaraci\u00f3n de nulidad no afectar\u00e1 a la validez del resto de disposiciones recogidas en las presentes Condiciones Generales.<\/p>\n<p><\/p>\n<p>12.- Ley\u00a0 y Jurisdicci\u00f3n aplicable<br>Las presentes Condiciones Generales se rigen e interpretan de acuerdo con la ley espa\u00f1ola.<br>En el caso de que se produzca cualquier tipo de discrepancia o reclamaci\u00f3n entre las partes en relaci\u00f3n con el cumplimiento o el contenido de las presentes Condiciones Generales, las partes acuerdan someter la decisi\u00f3n del asunto planteado a los Juzgados y Tribunales de Barcelona.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>C o n d i c i o n e s d e C o m p r a Condiciones de compra Estas condiciones constituyen las condiciones generales de compra de la compa\u00f1\u00eda Can Vall\u00e8s S.L.U (en adelante, Can Vall\u00e8s) que comercializa los productos a trav\u00e9s del sitio web http:\/\/canvalles.com 1.- Objeto y generalidades Las&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-988065","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/pages\/988065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/comments?post=988065"}],"version-history":[{"count":3,"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/pages\/988065\/revisions"}],"predecessor-version":[{"id":990062,"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/pages\/988065\/revisions\/990062"}],"wp:attachment":[{"href":"https:\/\/canvalles.com\/ca\/wp-json\/wp\/v2\/media?parent=988065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}